{"id":1229,"count":2,"description":"","link":"https:\/\/www.romaoggi.eu\/index.php\/tag\/letizia-volpicelli\/","name":"Letizia Volpicelli","slug":"letizia-volpicelli","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Letizia Volpicelli Archivi - roma oggi<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Letizia Volpicelli Archivi - roma oggi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.romaoggi.eu\/index.php\/tag\/letizia-volpicelli\/\" \/>\n<meta property=\"og:site_name\" content=\"roma oggi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@romaoggi_eu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/index.php\\\/tag\\\/letizia-volpicelli\\\/\",\"url\":\"https:\\\/\\\/www.romaoggi.eu\\\/index.php\\\/tag\\\/letizia-volpicelli\\\/\",\"name\":\"Letizia Volpicelli Archivi - roma oggi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/index.php\\\/tag\\\/letizia-volpicelli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/index.php\\\/tag\\\/letizia-volpicelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.romaoggi.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Letizia Volpicelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.romaoggi.eu\\\/\",\"name\":\"roma oggi\",\"description\":\"Interesting News for Interesting people\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.romaoggi.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/#organization\",\"name\":\"RomaOggi\",\"url\":\"https:\\\/\\\/www.romaoggi.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.romaoggi.eu\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logowp.jpg\",\"contentUrl\":\"https:\\\/\\\/www.romaoggi.eu\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logowp.jpg\",\"width\":300,\"height\":133,\"caption\":\"RomaOggi\"},\"image\":{\"@id\":\"https:\\\/\\\/www.romaoggi.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RomaOggi-841544845954114\",\"https:\\\/\\\/x.com\\\/romaoggi_eu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Letizia Volpicelli Archivi - roma oggi","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Letizia Volpicelli Archivi - roma oggi","og_url":"https:\/\/www.romaoggi.eu\/index.php\/tag\/letizia-volpicelli\/","og_site_name":"roma oggi","twitter_card":"summary_large_image","twitter_site":"@romaoggi_eu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.romaoggi.eu\/index.php\/tag\/letizia-volpicelli\/","url":"https:\/\/www.romaoggi.eu\/index.php\/tag\/letizia-volpicelli\/","name":"Letizia Volpicelli Archivi - roma oggi","isPartOf":{"@id":"https:\/\/www.romaoggi.eu\/#website"},"breadcrumb":{"@id":"https:\/\/www.romaoggi.eu\/index.php\/tag\/letizia-volpicelli\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.romaoggi.eu\/index.php\/tag\/letizia-volpicelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.romaoggi.eu\/"},{"@type":"ListItem","position":2,"name":"Letizia Volpicelli"}]},{"@type":"WebSite","@id":"https:\/\/www.romaoggi.eu\/#website","url":"https:\/\/www.romaoggi.eu\/","name":"roma oggi","description":"Interesting News for Interesting people","publisher":{"@id":"https:\/\/www.romaoggi.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.romaoggi.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.romaoggi.eu\/#organization","name":"RomaOggi","url":"https:\/\/www.romaoggi.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.romaoggi.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.romaoggi.eu\/wp-content\/uploads\/2017\/04\/logowp.jpg","contentUrl":"https:\/\/www.romaoggi.eu\/wp-content\/uploads\/2017\/04\/logowp.jpg","width":300,"height":133,"caption":"RomaOggi"},"image":{"@id":"https:\/\/www.romaoggi.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RomaOggi-841544845954114","https:\/\/x.com\/romaoggi_eu"]}]}},"_links":{"self":[{"href":"https:\/\/www.romaoggi.eu\/index.php\/wp-json\/wp\/v2\/tags\/1229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romaoggi.eu\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.romaoggi.eu\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.romaoggi.eu\/index.php\/wp-json\/wp\/v2\/posts?tags=1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}